{"id":372,"date":"2012-03-20T11:57:08","date_gmt":"2012-03-20T10:57:08","guid":{"rendered":"http:\/\/www.akw-fitness.de\/blog\/?p=372"},"modified":"2023-02-08T17:59:06","modified_gmt":"2023-02-08T15:59:06","slug":"bali-marathon-extremsport-auf-der-insel-der-goetter","status":"publish","type":"post","link":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html","title":{"rendered":"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter"},"content":{"rendered":"<p>Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange Sandstr\u00e4nde und Hotels der internationalen Spitzenklasse. An Sport denkt der Tourist dabei eher nicht, au\u00dfer nat\u00fcrlich an das Tauchen und Surfen. Was der Reisende dort kaum erwartet, ist ein Marathon von internationalem Format. Aber es gibt ihn unter der Bezeichnung &#8222;Bali Marathon&#8220;.<!--more--><\/p>\n<h2>Lange Anreise nach Bali, Akklimatisation notwendig<\/h2>\n<p>Der letzte Lauf startet am 22. April 2012, nach dem Ende der Regenzeit. Die beschert der Insel Bali n\u00e4mlich eine Menge Wasser von oben, was so manche Stra\u00dfe schon mal unpassierbar macht. K\u00fchler wird es allerdings nicht, auf Bali ist es immer um die 28 \u00b0C warm, bei hoher Luftfeuchtigkeit. Gutes Training und einige Zeit der Akklimatisation vor Ort. Denn zum anstrengenden Klima kommt die lange Anreise von Deutschland aus, es k\u00f6nnen schon mal 16 Stunden reine Flugzeit sein, plus Zwischenstopps und Wartezeit bei der Einreise.<\/p>\n<p>Wer um die halbe Welt fliegt m\u00f6chte auch ein paar Tage in den Touristenorten im S\u00fcden der Insel in Sanur, Kuta oder Nusa Dua ausspannen. Im S\u00fcden findet auch der Lauf statt, in der N\u00e4he des Bali Safari and Marine Park, \u00f6stlich der Inselhauptstadt Denpasar und etwas n\u00f6rdlich des Touristenortes Sanur. Es geht am Strand entlang, aber auch durch das Hinterland, vorbei an D\u00f6rfern durch die traumhaft sch\u00f6ne balinesische Landschaft.<\/p>\n<h2>Einreise problemlos, Risiken: Malaria und Tollwut<\/h2>\n<p>Wer teilnehmen m\u00f6chte, sollte sich schnellstens anmelden, die Einreise nach Bali ist mit deutscher Staatsb\u00fcrgerschaft denkbar einfach. Der Reisepass muss zum Reisezeitpunkt noch 6 Monate g\u00fcltig sein und zwei freie Seiten haben, ein Touristenvisum gibt es direkt vor Ort am Flughafen.<\/p>\n<p>Es gilt 30 Tage, kostet aktuell 25 USD und sollte auch in USD bezahlt werden. Alles andere kostet unn\u00f6tige Zeit, die am Strand sicher angenehmer verbracht werden kann. Gesundheitsrisiken gibt es auf Bali au\u00dfer dem tropischen Klima kaum, die Malariagefahr ist zwar vorhanden aber nicht extrem hoch, vor Tieren gilt es sich in Acht zu nehmen. Bali ist Tollwutgebiet.<\/p>\n<p>Alles weitere wie Impfungen oder pers\u00f6nliche Risiken sollten vorher idealerweise mit einem Arzt abgekl\u00e4rt werden.<\/p>\n<p>Die offizielle Website des Bali Marathon findet sich unter: <a href=\"http:\/\/www.balimarathon.com\/\" target=\"_blank\" rel=\"noopener\">www.balimarathon.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange Sandstr\u00e4nde und Hotels der internationalen Spitzenklasse. An Sport denkt der Tourist dabei eher nicht, au\u00dfer nat\u00fcrlich an das Tauchen und Surfen. Was der Reisende dort kaum erwartet, ist ein Marathon von internationalem Format. Aber es gibt <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[358],"class_list":["post-372","post","type-post","status-publish","format-standard","hentry","category-ausdauertraining","tag-marathon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter<\/title>\n<meta name=\"description\" content=\"Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter\" \/>\n<meta property=\"og:description\" content=\"Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html\" \/>\n<meta property=\"og:site_name\" content=\"Blog - AKW Fitness\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AKWFitness\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-20T10:57:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T15:59:06+00:00\" \/>\n<meta name=\"author\" content=\"master\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@akw_fitness\" \/>\n<meta name=\"twitter:site\" content=\"@akw_fitness\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"master\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html\"},\"author\":{\"name\":\"master\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#\\\/schema\\\/person\\\/a56a1e298187a5bfaaceb1f80777c98b\"},\"headline\":\"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter\",\"datePublished\":\"2012-03-20T10:57:08+00:00\",\"dateModified\":\"2023-02-08T15:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#organization\"},\"keywords\":[\"marathon\"],\"articleSection\":[\"Ausdauertraining\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html\",\"url\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html\",\"name\":\"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#website\"},\"datePublished\":\"2012-03-20T10:57:08+00:00\",\"dateModified\":\"2023-02-08T15:59:06+00:00\",\"description\":\"Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/ausdauertraining\\\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/\",\"name\":\"Blog - AKW Fitness\",\"description\":\"Blog - AKW Fitness\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#organization\",\"name\":\"AKW Fitness & Sport Handels-GmbH\",\"url\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/logo.png\",\"width\":168,\"height\":61,\"caption\":\"AKW Fitness & Sport Handels-GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AKWFitness\\\/\",\"https:\\\/\\\/x.com\\\/akw_fitness\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwjhjjGbjpP-K_-4X0b5Uhg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.akw-fitness.de\\\/blog\\\/#\\\/schema\\\/person\\\/a56a1e298187a5bfaaceb1f80777c98b\",\"name\":\"master\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter","description":"Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html","og_locale":"de_DE","og_type":"article","og_title":"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter","og_description":"Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange","og_url":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html","og_site_name":"Blog - AKW Fitness","article_publisher":"https:\/\/www.facebook.com\/AKWFitness\/","article_published_time":"2012-03-20T10:57:08+00:00","article_modified_time":"2023-02-08T15:59:06+00:00","author":"master","twitter_card":"summary_large_image","twitter_creator":"@akw_fitness","twitter_site":"@akw_fitness","twitter_misc":{"Verfasst von":"master","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#article","isPartOf":{"@id":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html"},"author":{"name":"master","@id":"https:\/\/www.akw-fitness.de\/blog\/#\/schema\/person\/a56a1e298187a5bfaaceb1f80777c98b"},"headline":"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter","datePublished":"2012-03-20T10:57:08+00:00","dateModified":"2023-02-08T15:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/www.akw-fitness.de\/blog\/#organization"},"keywords":["marathon"],"articleSection":["Ausdauertraining"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html","url":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html","name":"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter","isPartOf":{"@id":"https:\/\/www.akw-fitness.de\/blog\/#website"},"datePublished":"2012-03-20T10:57:08+00:00","dateModified":"2023-02-08T15:59:06+00:00","description":"Bali, die Insel der G\u00f6tter oder auch die Insel der zehntausend Tempel, ist bekannt f\u00fcr seine vielf\u00e4ltige und exotische Kultur, das tropische Klima, lange","breadcrumb":{"@id":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.akw-fitness.de\/blog\/ausdauertraining\/bali-marathon-extremsport-auf-der-insel-der-goetter.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.akw-fitness.de\/blog"},{"@type":"ListItem","position":2,"name":"Bali Marathon \u2013 Extremsport auf der Insel der G\u00f6tter"}]},{"@type":"WebSite","@id":"https:\/\/www.akw-fitness.de\/blog\/#website","url":"https:\/\/www.akw-fitness.de\/blog\/","name":"Blog - AKW Fitness","description":"Blog - AKW Fitness","publisher":{"@id":"https:\/\/www.akw-fitness.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.akw-fitness.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.akw-fitness.de\/blog\/#organization","name":"AKW Fitness & Sport Handels-GmbH","url":"https:\/\/www.akw-fitness.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.akw-fitness.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.akw-fitness.de\/blog\/wp-content\/uploads\/2014\/08\/logo.png","contentUrl":"https:\/\/www.akw-fitness.de\/blog\/wp-content\/uploads\/2014\/08\/logo.png","width":168,"height":61,"caption":"AKW Fitness & Sport Handels-GmbH"},"image":{"@id":"https:\/\/www.akw-fitness.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AKWFitness\/","https:\/\/x.com\/akw_fitness","https:\/\/www.youtube.com\/channel\/UCwjhjjGbjpP-K_-4X0b5Uhg"]},{"@type":"Person","@id":"https:\/\/www.akw-fitness.de\/blog\/#\/schema\/person\/a56a1e298187a5bfaaceb1f80777c98b","name":"master"}]}},"_links":{"self":[{"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/posts\/372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/comments?post=372"}],"version-history":[{"count":6,"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/posts\/372\/revisions"}],"predecessor-version":[{"id":2617,"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/posts\/372\/revisions\/2617"}],"wp:attachment":[{"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/media?parent=372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/categories?post=372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.akw-fitness.de\/blog\/wp-json\/wp\/v2\/tags?post=372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}